{"id":89993,"date":"2025-10-07T13:37:57","date_gmt":"2025-10-07T11:37:57","guid":{"rendered":"https:\/\/www.solanaibiza.com\/?post_type=properties&#038;p=89993"},"modified":"2026-04-23T12:48:23","modified_gmt":"2026-04-23T10:48:23","slug":"cas-graner","status":"publish","type":"properties","link":"https:\/\/www.solanaibiza.com\/fr\/ibiza-properties\/cas-graner\/","title":{"rendered":"CAS GRANER"},"content":{"rendered":"\n<p><strong>VENDU<\/strong><br><br>Situ\u00e9e dans un quartier r\u00e9sidentiel calme de Port des Torrent, cette villa de style contemporain s\u00e9duit par sa luminosit\u00e9, ses grands volumes et son environnement privil\u00e9gi\u00e9. Elle se trouve \u00e0 seulement 500 m\u00e8tres de la plage et \u00e0 5 minutes en voiture des c\u00e9l\u00e8bres Cala Bassa et Cala Conta, deux des criques les plus embl\u00e9matiques de l\u2019\u00eele.<\/p>\n\n\n\n<p>La propri\u00e9t\u00e9 repose sur un terrain urbain de 1 781 m\u00b2, enti\u00e8rement cl\u00f4tur\u00e9 et dot\u00e9 de deux portails d\u2019acc\u00e8s ind\u00e9pendants.<\/p>\n\n\n\n<p>Construite au d\u00e9but des ann\u00e9es 1980, la villa offre une surface habitable d\u2019environ 270 m\u00b2, avec des pi\u00e8ces spacieuses et tr\u00e8s lumineuses, ainsi que de grandes terrasses couvertes ouvertes sur le jardin.<\/p>\n\n\n\n<p>De plain-pied, la maison principale dispose d\u2019un vaste espace ouvert comprenant un salon avec chemin\u00e9e, un salon TV, une salle \u00e0 manger et une cuisine ouverte. Sur ce m\u00eame niveau se trouvent trois chambres doubles, une salle de bains compl\u00e8te et une salle de douche.<\/p>\n\n\n\n<p>Ind\u00e9pendamment de la maison principale, la propri\u00e9t\u00e9 comprend un appartement annexe d\u2019environ 50 m\u00b2, id\u00e9al pour recevoir des invit\u00e9s ou pour le personnel.<\/p>\n\n\n\n<p>Attenante \u00e0 la maison principale, une grande salle d\u2019environ 40 m\u00b2 avec salle \u00e0 manger et espace barbecue constitue l\u2019endroit parfait pour partager des moments conviviaux en famille ou entre amis.<\/p>\n\n\n\n<p>Un escalier ext\u00e9rieur m\u00e8ne \u00e0 un atelier ou studio ind\u00e9pendant d\u2019environ 17 m\u00b2, situ\u00e9 \u00e0 l\u2019\u00e9tage sup\u00e9rieur.<\/p>\n\n\n\n<p>Parmi ses \u00e9quipements et caract\u00e9ristiques :<br>\u2022PISCINE de 26 m\u00b2<br>\u2022F\u00caNETRES EN ALUMINIUM avec DOUBLE VITRAGE<br>\u2022RACCORDEMENT AU R\u00c9SEAU D\u00b4ASSAINESSEMENT<br>\u2022GRANDS PLACARD ENCASTR\u00c9S dans toutes les chambres<br>\u2022GARAGE pour un v\u00e9hicule<br>\u2022LOCAL DE RANGEMENT<br>\u2022JARDIN M\u00c9DITERRAN\u00c9EN avec palmiers, washingtonias, cypr\u00e8s, gen\u00e9vriers et plantes grasses<\/p>\n\n\n\n<p>Une villa pleine de charme et de potentiel, id\u00e9ale pour ceux qui recherchent espace, intimit\u00e9 et confort, \u00e0 proximit\u00e9 de la mer et de nombreuses commodit\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n","protected":false},"featured_media":89941,"template":"","meta":{"_acf_changed":false},"categories":[60,84],"tags":[232,241,199,200,211],"class_list":["post-89993","properties","type-properties","status-publish","has-post-thumbnail","hentry","category-maisons","category-rural-houses-fr","tag-for-sale-home-fr","tag-house-for-sale-fr","tag-nouvelle-saison","tag-propriete-a-vendre","tag-venta-villas-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/properties\/89993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/types\/properties"}],"version-history":[{"count":0,"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/properties\/89993\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/media\/89941"}],"wp:attachment":[{"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=89993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/categories?post=89993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/tags?post=89993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}