{"id":26960,"date":"2022-11-25T13:51:47","date_gmt":"2022-11-25T12:51:47","guid":{"rendered":"https:\/\/www.solanaibiza.com\/ibiza-properties\/vc-078-can-bikini\/"},"modified":"2024-11-25T13:44:32","modified_gmt":"2024-11-25T12:44:32","slug":"vc-078-can-bikini","status":"publish","type":"properties","link":"https:\/\/www.solanaibiza.com\/fr\/ibiza-properties\/finca-vendre-santa-agnes-ibiza\/","title":{"rendered":"VENDU"},"content":{"rendered":"\n<p>Au c\u0153ur des for\u00eats de pins dehors le pittoresque village de Santa Agnes, Can Bikini est situ\u00e9e dans un cadre rural et paisible, s&rsquo;\u00e9tendant sur 13 000 m2 de terrain avec une authentique finca ibicenca restaur\u00e9e et modernis\u00e9e avec style, deux maisons d&rsquo;h\u00f4tes et une petite maison ind\u00e9pendante qui marie une architecture moderne \u00e0 l&rsquo;utilisation de mat\u00e9riaux naturels typiques des constructions m\u00e9diterran\u00e9ennes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">EMPLACEMENT ET ENVIRONNEMENT<\/h2>\n\n\n\n<p>Santa Agnes est l&rsquo;un des derniers coins d&rsquo;Ibiza o\u00f9 il n&rsquo;y a presque aucun d\u00e9veloppement urbain ou commercial, pr\u00e9servant une authenticit\u00e9 rurale \u00e9troitement li\u00e9e \u00e0 la terre. Cette r\u00e9gion est r\u00e9put\u00e9e pour sa c\u00e9l\u00e8bre floraison des amandiers, lorsque le paysage se couvre d&rsquo;innombrables fleurs blanches. La r\u00e9gion offre d&rsquo;innombrables opportunit\u00e9s de randonn\u00e9e, de course \u00e0 pied, de VTT et de cyclisme sur route.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">AM\u00c9NAGEMENT<\/h2>\n\n\n\n<p>L&rsquo;espace principal de la maison est spacieux et lumineux, avec des plafonds de quatre m\u00e8tres de haut et de grandes baies vitr\u00e9es s&rsquo;ouvrant sur de vastes terrasses couvertes avec vue sur le paysage luxuriant. Il y a une chemin\u00e9e pr\u00eate pour les mois d&rsquo;hiver et un coin lecture habilement sculpt\u00e9 dans les \u00e9pais murs blanchis \u00e0 la chaux. La cuisine moderne de Doca est \u00e9quip\u00e9e d&rsquo;appareils Gaggenau.<br>Au rez-de-chauss\u00e9e, on trouve 2 chambres avec leurs salles de bains attenantes et un acc\u00e8s \u00e0 des terrasses d\u00e9couvertes. La chambre principale est situ\u00e9e \u00e0 l&rsquo;\u00e9tage sup\u00e9rieur avec sa salle de bains attenante et une charmante terrasse offrant une vue sur les collines verdoyantes et la mer au loin.<br>B\u00e9n\u00e9ficiant d&rsquo;une v\u00e9ritable intimit\u00e9, vous trouverez une cabane d&rsquo;invit\u00e9s balinaise qui abrite une spacieuse chambre d&rsquo;amis. \u00c0 l&rsquo;ext\u00e9rieur, de luxuriantes plantes de bambou encadrent une salle de bains en plein air avec une baignoire en bois et un lavabo en pierre grise.<br>Depuis la maison principale, on acc\u00e8de \u00e0 une deuxi\u00e8me maison d&rsquo;h\u00f4tes climatis\u00e9e avec une fa\u00e7ade en pierre de couleur sable refl\u00e9tant les teintes douces de l&rsquo;int\u00e9rieur. Une petite maison ind\u00e9pendante, avec sa propre cuisine, chambre et salle de bains, compl\u00e8te cette \u00e9l\u00e9gante propri\u00e9t\u00e9 insulaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">EXT\u00c9RIEUR ET JARDIN<\/h2>\n\n\n\n<p>Une piscine \u00e0 d\u00e9bordement turquoise est entour\u00e9e d&rsquo;un paysage luxuriant et d&rsquo;un jardin bien entretenu, ainsi que de plusieurs coins de d\u00e9tente. Une authentique maison de piscine en bois vo\u00fbt\u00e9e est \u00e9quip\u00e9e d&rsquo;un bar ext\u00e9rieur, d&rsquo;un barbecue et d&rsquo;un four \u00e0 pizza, \u00e0 c\u00f4t\u00e9 d&rsquo;une salle \u00e0 manger d&rsquo;\u00e9t\u00e9.<br>Le relief du terrain est assez uniforme, permettant une utilisation compl\u00e8te du terrain, avec diff\u00e9rents coins id\u00e9aux pour les jeux d&rsquo;enfants, les zones de cabane dans les arbres ou de vastes espaces parfaits pour des \u00e9v\u00e9nements sp\u00e9ciaux et des divertissements.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">ID\u00c9ALE POUR<\/h2>\n\n\n\n<p>Ceux qui appr\u00e9cient la vie priv\u00e9e et la tranquillit\u00e9 au milieu de la nature luxuriante, dans une \u00e9l\u00e9gante et confortable finca situ\u00e9e dans une authentique r\u00e9gion ibicenca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">CARACT\u00c9RISTIQUES ADDITIONNELLES<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Puits d&rsquo;eau priv\u00e9<\/li>\n\n\n\n<li>\u00c9lectricit\u00e9 du r\u00e9seau<\/li>\n\n\n\n<li>Chauffage au sol<\/li>\n\n\n\n<li>Climatisation<\/li>\n\n\n\n<li>Chemin\u00e9e<\/li>\n\n\n\n<li>Buanderie<\/li>\n\n\n\n<li>Espace de stockage<\/li>\n\n\n\n<li>Salle de sport en plein air<\/li>\n\n\n\n<li>Plateforme de yoga<\/li>\n<\/ul>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"categories":[60,134,84],"tags":[241,202,200],"class_list":["post-26960","properties","type-properties","status-publish","hentry","category-maisons","category-maisons-luxe","category-rural-houses-fr","tag-house-for-sale-fr","tag-maisons-de-luxe-a-vendre","tag-propriete-a-vendre"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/properties\/26960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/types\/properties"}],"version-history":[{"count":0,"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/properties\/26960\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=26960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/categories?post=26960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solanaibiza.com\/fr\/wp-json\/wp\/v2\/tags?post=26960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}