{"id":32673,"date":"2024-01-15T13:05:16","date_gmt":"2024-01-15T12:05:16","guid":{"rendered":"https:\/\/www.solanaibiza.com\/ibiza-rentals\/ac-120-villa-art\/"},"modified":"2024-06-19T13:07:11","modified_gmt":"2024-06-19T11:07:11","slug":"ac-120-villa-art","status":"publish","type":"rentals","link":"https:\/\/www.solanaibiza.com\/es\/ibiza-rentals\/villa-moderna-en-alquiler-vista-mar-san-jose-ibiza\/","title":{"rendered":"Villa moderna en alquiler con vistas al mar en San Jos\u00e9 Ibiza"},"content":{"rendered":"\n<p>Descubra un rinc\u00f3n paradis\u00edaco en la isla blanca con esta magn\u00edfica villa de arquitectura moderna, presentada por Solana Ibiza. Sum\u00e9rjase en un oasis de elegancia y comodidad, donde cada detalle ha sido cuidadosamente dise\u00f1ado para ofrecer una experiencia inigualable. Rodeada de calma, verdor y con vistas panor\u00e1micas al mar y la costa hasta la m\u00e1gica isla de Formentera, esta propiedad es un sue\u00f1o hecho realidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">UBICACI\u00d3N Y ENTORNO<\/h2>\n\n\n\n<p>Ubicada en la codiciada regi\u00f3n suroeste de la isla, entre Es Cubells y Cap Llentrisca, esta villa se erige en un terreno de 10,000 m2 totalmente vallado con una puerta de acceso de apertura autom\u00e1tica. Bellas y reconocidas playas como Es Cubells, Es Torrent y Cala d&#8217;Hort se encuentran a unos minutos en coche, mientras que la cercana tienda Can Mestre ofrece no solo comestibles sino tambi\u00e9n prensa internacional y aut\u00e9ntica cocina local. San Jos\u00e9, con sus comercios, bares y restaurantes, est\u00e1 a 10 min. en coche, el aeropuerto a 10 km y la ciudad de Ibiza a 12 km.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">DISTRIBUCI\u00d3N<\/h2>\n\n\n\n<p>Esta magn\u00edfica villa de una sola planta ofrece un dise\u00f1o que combina comodidad y elegancia. Desde el vest\u00edbulo, una estilosa puerta de madera te invita al amplio sal\u00f3n-comedor lleno de luz, conectando perfectamente con el jard\u00edn y las impresionantes vistas al mar gracias a los grandes ventanales. La moderna cocina integrada y el aseo de invitados a\u00f1aden un toque de funcionalidad y conveniencia.<br>La habitaci\u00f3n principal, con vistas al mar, vestidor y ba\u00f1o en suite, se convierte en un oasis con acceso directo al jard\u00edn y una terraza privada. Una habitaci\u00f3n doble con cuarto de ducha ofrece vistas al patio, mientras que otras dos habitaciones dobles independientes, cada una con su propia entrada, garantizan privacidad a los invitados. Una quinta habitaci\u00f3n doble independiente en el jard\u00edn completa esta joya mediterr\u00e1nea con su cuarto de ducha y una amplia terraza descubierta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">EXTERIORES Y JARD\u00cdN<\/h2>\n\n\n\n<p>Disfrute de los d\u00edas soleados en la amplia piscina desbordante de 20 m x 4 m, rodeada de terrazas en piedra natural y complementada por una ducha exterior. La cocina de verano con barbacoa y frigor\u00edfico ofrece un espacio perfecto para las celebraciones con amigos y la familia. El cuidado y exuberante jard\u00edn, con una amplia extensi\u00f3n de c\u00e9sped frente a la casa y una variedad de plantas mediterr\u00e1neas, crea un oasis de frescor y serenidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">CARACTER\u00cdSTICAS ADICIONALES<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aire acondicionado<\/li>\n\n\n\n<li>Armarios empotrados<\/li>\n\n\n\n<li>Lavadero con lavadora, secadora y frigor\u00edfico adicional.<\/li>\n\n\n\n<li>Wifi<\/li>\n\n\n\n<li>Sistema de sonido interior y el jard\u00edn<\/li>\n<\/ul>\n\n\n\n<p>No pierda la oportunidad de vivir la experiencia de disfrutar las comodidades, dise\u00f1o elegante y el entorno natural que rodean esta propiedad. Contacte con nosotros hoy para programar una visita o obtener m\u00e1s informaci\u00f3n llamando al +34 607 902612 o escribiendo a info@solanaibiza.com. Su para\u00edso en Ibiza le espera.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n\n\n<p>\u00a0<\/p>\n<p>Licencia tur\u00edstica: ETV-0933-E<\/p>","protected":false},"featured_media":76567,"template":"","tags":[143,171,260,261],"rental_category":[87],"filtro":[106,111,109],"class_list":["post-32673","rentals","type-rentals","status-publish","has-post-thumbnail","hentry","tag-alquiler","tag-alquiler-con-piscina","tag-property-rentals-es","tag-rental-villas-es","rental_category-villa-es","filtro-alquiler-vacacional","filtro-alquiler-vacacional-ibiza","filtro-alquiler-vacacional-villas"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/rentals\/32673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/rentals"}],"about":[{"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/types\/rentals"}],"version-history":[{"count":0,"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/rentals\/32673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/media\/76567"}],"wp:attachment":[{"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/media?parent=32673"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/tags?post=32673"},{"taxonomy":"rental_category","embeddable":true,"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/rental_category?post=32673"},{"taxonomy":"filtro","embeddable":true,"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/filtro?post=32673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}