{"id":73321,"date":"2023-11-15T13:32:00","date_gmt":"2023-11-15T12:32:00","guid":{"rendered":"https:\/\/www.solanaibiza.com\/?post_type=properties&#038;p=73321"},"modified":"2025-09-03T17:22:42","modified_gmt":"2025-09-03T15:22:42","slug":"vc-005-can-ragusa-2","status":"publish","type":"properties","link":"https:\/\/www.solanaibiza.com\/es\/ibiza-properties\/casa-venta-vistas-mar-san-jose\/","title":{"rendered":"VC-005 CAN RAGUSA"},"content":{"rendered":"\n<p>Casa de campo con vistas al mar cerca de la playa de Cala Bassa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">ACCESO, ENTRADA Y PARKING<\/h2>\n\n\n\n<p>El acceso a esta magn\u00edfica propiedad se realiza a trav\u00e9s de un port\u00f3n el\u00e9ctrico que conduce a una parcela completamente vallada. Un amplio garaje ofrece espacio para dos coches.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">DISTRIBUCI\u00d3N<\/h2>\n\n\n\n<p>Esta encantadora casa de una sola planta cuenta con 3 habitaciones, cada una con su propio ba\u00f1o \u00aben suite\u00bb, y ofrece la posibilidad de transformar un amplio garaje doble en una c\u00f3moda casa de invitados.<br>La espaciosa sala de estar, con un comedor separado y una cocina abierta, brinda acceso directo a la amplia terraza exterior con piscina y una relajante cascada de agua.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">EXTERIORES<\/h2>\n\n\n\n<p>Aqu\u00ed, se encuentran diversas \u00e1reas de estar, una generosa mesa de comedor, tumbonas y una refrescante ducha al aire libre. Adem\u00e1s, la piscina est\u00e1 equipada para ser disfrutada incluso durante los meses invernales.<br>La propiedad en su totalidad puede ser recorrida a trav\u00e9s de un encantador camino verde que conduce a varios rincones con vistas espectaculares. Un estanque con nen\u00fafares y una terraza en la azotea con vistas panor\u00e1micas de 180 grados invitan al descanso y la contemplaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">EQUIPAMIENTO<\/h2>\n\n\n\n<p>La propiedad est\u00e1 equipada con agua y luz de red. Y, durante los frescos meses de invierno, podr\u00e1s disfrutar de un c\u00e1lido ambiente gracias al suelo radiante, mientras que en verano, el aire acondicionado en las habitaciones garantiza temperaturas agradables.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">UBICACI\u00d3N, VISTAS Y ORIENTACI\u00d3N<\/h2>\n\n\n\n<p>Orientada al oeste, esta c\u00e1lida casa ofrece preciosas vistas al mar. A tan solo unos minutos en coche, podr\u00e1s llegar a las hermosas calas de Cala Bassa, Cala Conta y Cala Tarida, cada una con sus restaurantes de primera clase. A poca distancia, tambi\u00e9n encontrar\u00e1s restaurantes cercanos y un supermercado bien surtido. La animada ciudad de San Jos\u00e9 est\u00e1 a solo 10 minutos en coche.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">IDEAL PARA<\/h2>\n\n\n\n<p>Esta casa no solo ofrece comodidad y elegancia, sino tambi\u00e9n la oportunidad de sumergirse por completo en el estilo de vida mediterr\u00e1neo. \u00a1Haz realidad tu sue\u00f1o de vivir en este para\u00edso!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n","protected":false},"featured_media":73322,"template":"","meta":{"_acf_changed":false},"categories":[61],"tags":[146],"class_list":["post-73321","properties","type-properties","status-publish","has-post-thumbnail","hentry","category-casas","tag-en-venta"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/properties\/73321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/types\/properties"}],"version-history":[{"count":0,"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/properties\/73321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/media\/73322"}],"wp:attachment":[{"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/media?parent=73321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/categories?post=73321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solanaibiza.com\/es\/wp-json\/wp\/v2\/tags?post=73321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}