{"id":31950,"date":"2021-04-13T12:46:24","date_gmt":"2021-04-13T10:46:24","guid":{"rendered":"https:\/\/www.solanaibiza.com\/ibiza-rentals\/ac-009-casa-fabio\/"},"modified":"2025-04-21T11:33:55","modified_gmt":"2025-04-21T09:33:55","slug":"ac-009-casa-fabio","status":"publish","type":"rentals","link":"https:\/\/www.solanaibiza.com\/de\/ibiza-rentals\/ac-009-casa-fabio\/","title":{"rendered":"AC-009 CASA FABIO"},"content":{"rendered":"<div id=\"description_de\" class=\"tab-pane active\" role=\"tabpanel\">\n<div id=\"description_de\" class=\"tab-pane active\" role=\"tabpanel\">\n<p>Luxusvilla in ruhiger Umgebung mit herrlichem Meerblick, in der N\u00e4he der Stadt Ibiza und der ber\u00fchmten Str\u00e4nde von Salinas und Cala Jondal. Das stilvolle und moderne Anwesen ist von \u00fcppigen G\u00e4rten und einem sch\u00f6nen Innenhof umgeben, um ein echtes mediterranes Wohngef\u00fchl zu bieten.<\/p>\n<p>Wohnbereiche<\/p>\n<p>\u2022 Das Wohnzimmer verf\u00fcgt \u00fcber einen versunkenen Sitzbereich am Kamin.<br \/>\n\u2022 Ein weiterer Sitzbereich verf\u00fcgt \u00fcber einen Fernseher mit UK-Satellit und ein B &amp; O-Soundsystem.<br \/>\nVom Boden bis zur Decke reichende Schiebefenster schaffen ein Gef\u00fchl des Lebens im Freien und bieten einen sehr sch\u00f6nen Meerblick.<\/p>\n<p>Der Innenhof verf\u00fcgt \u00fcber mehrere schattige Sitzbereiche und bietet Blick auf den Garten mit Orangenb\u00e4umen, Lavendel und einem Zierbrunnen.<\/p>\n<p>K\u00fcche<\/p>\n<p>Stilvolle voll ausgestattete K\u00fcche mit Fr\u00fchst\u00fcckstheke, Tisch und St\u00fchlen, TV, Backofen, Herd, Mikrowelle, K\u00fchlschrank mit Gefrierfach und Gaggenau Weink\u00fchler.<br \/>\nSchlafzimmer und Badezimmer<\/p>\n<p>Haupthaus<br \/>\n\u2022 Hauptschlafzimmer mit Ankleidebereich, Sat-TV, privater Terrasse und eigenem Bad mit luxuri\u00f6ser Badewanne f\u00fcr zwei Personen<br \/>\n\u2022 Doppelzimmer mit superking Bett, raumhohen Fenstern mit Blick auf das Meer, en-suite Badezimmer mit Badewanne und ebenerdiger Dusche.<\/p>\n<p>Schlafzimmer im Innenhof:<br \/>\n\u2022 2 x Doppelzimmer mit King Bett und en-suite Duschbad<\/p>\n<p>Garten Schlafzimmer:<br \/>\n\u2022 Doppelzimmer mit King Bett und en-suite Duschbad<br \/>\n\u2022 Doppelzimmer mit zwei Einzelbetten und en-suite Duschbad<\/p>\n<p>Alle Schlafzimmer verf\u00fcgen \u00fcber Klimaanlage, Kleiderschr\u00e4nke und iPod-Dockingstationen. Die 5 Doppelzimmer verf\u00fcgen alle \u00fcber super King gro\u00dfe Betten.<\/p>\n<p>Drau\u00dfen<\/p>\n<p>\u2022 Gro\u00dfer 12 x 6 m gro\u00dfer Salzwasser-Infinity-Pool<br \/>\n\u2022 Atemberaubender Meerblick in Richtung Salinas Beach<br \/>\n\u2022 Stilvolle Sonnenliegen<br \/>\n\u2022 Der Poolbereich verf\u00fcgt \u00fcber einen Grill, einen K\u00fchlschrank und eine iPod-Dockingstation<br \/>\n\u2022 \u00dcberdachte Terrasse mit sch\u00f6nem Esstisch und St\u00fchlen f\u00fcr 12 Personen<br \/>\n\u2022 Bequeme Sofas zum Entspannen<br \/>\n\u2022 Wundersch\u00f6n angelegte G\u00e4rten mit \u00fcppig gr\u00fcnen Rasenfl\u00e4chen, Obst- und Olivenb\u00e4umen, Brunnen mit duftendem Lavendel und Orangenb\u00e4umen<\/p>\n<p>Andere<\/p>\n<p>\u2022 Waschraum mit zwei Waschmaschinen, W\u00e4schetrockner, K\u00fchlschrank mit Gefrierfach, Backofen, B\u00fcgeleisen und B\u00fcgelbrett<br \/>\n\u2022 Elektrische Tor beim Betreten<br \/>\n\u2022 Alarmsystem<br \/>\n\u2022 W-Land<br \/>\n\u2022 UK-Satellitensystem<\/p>\n<\/div>\n<p>Tourist License : ETV-1470-E<\/p>\n<\/div>\n","protected":false},"featured_media":31980,"template":"","tags":[227,223,229],"rental_category":[88],"filtro":[128,131,132],"class_list":["post-31950","rentals","type-rentals","status-publish","has-post-thumbnail","hentry","tag-holiday-rentals-de","tag-immobilienvermietung","tag-rental-villas-de","rental_category-villa-de","filtro-ferienunterkuenfte","filtro-ferienunterkuenfte-ibiza","filtro-ferienvermietung-villen"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.solanaibiza.com\/de\/wp-json\/wp\/v2\/rentals\/31950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solanaibiza.com\/de\/wp-json\/wp\/v2\/rentals"}],"about":[{"href":"https:\/\/www.solanaibiza.com\/de\/wp-json\/wp\/v2\/types\/rentals"}],"version-history":[{"count":0,"href":"https:\/\/www.solanaibiza.com\/de\/wp-json\/wp\/v2\/rentals\/31950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solanaibiza.com\/de\/wp-json\/wp\/v2\/media\/31980"}],"wp:attachment":[{"href":"https:\/\/www.solanaibiza.com\/de\/wp-json\/wp\/v2\/media?parent=31950"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solanaibiza.com\/de\/wp-json\/wp\/v2\/tags?post=31950"},{"taxonomy":"rental_category","embeddable":true,"href":"https:\/\/www.solanaibiza.com\/de\/wp-json\/wp\/v2\/rental_category?post=31950"},{"taxonomy":"filtro","embeddable":true,"href":"https:\/\/www.solanaibiza.com\/de\/wp-json\/wp\/v2\/filtro?post=31950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}